{"id":460,"date":"2026-03-26T12:08:36","date_gmt":"2026-03-26T11:08:36","guid":{"rendered":"https:\/\/nueva.ibyc.es\/gestion\/"},"modified":"2026-04-30T09:45:22","modified_gmt":"2026-04-30T07:45:22","slug":"gestion","status":"publish","type":"page","link":"https:\/\/ibyc.es\/fr\/gestion\/","title":{"rendered":"Gestion"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.35)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/Gestion-integral-de-embarcaciones-de-recreo.webp\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb background_blend=\u00a0\u00bbdarken\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb250px||300px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb100px||100px||true|false\u00a0\u00bb background_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dsm_block_reveal_text block_reveal_text=\u00a0\u00bbGestion et immatriculation de bateaux de plaisance\u00a0\u00bb heading_html_tag=\u00a0\u00bbh1&Prime; block_reveal_color=\u00a0\u00bbRGBA(255,255,255,0.2)\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb45px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb60px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb50px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_block_reveal_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb&#8211;et_global_body_font||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>D\u00e9marches, immatriculation et coordination administrative pour les bateaux \u00e0 usage priv\u00e9 ou commercial, avec une couverture nationale et internationale.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/ibyc.es\/fr\/contact\/\u00a0\u00bb button_text=\u00a0\u00bbDemander un service de gestion\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#032F3A\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb28px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text quote_border_color=\u00a0\u00bbgcid-primary-color\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-primary-color%22:%91%22quote_border_color%22%93}\u00a0\u00bb]<\/p>\n<blockquote>\n<p>Chez IBYC, nous g\u00e9rons toutes les d\u00e9marches li\u00e9es au Registre Maritime Espagnol pour les bateaux et navires de plaisance, qu\u2019ils soient destin\u00e9s \u00e0 un usage priv\u00e9 ou commercial.<\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Nous prenons en charge les pavillons, immatriculations, changements de propri\u00e9t\u00e9, autorisations de charter, certificats, inspections et liquidations fiscales, en offrant une gestion r\u00e9active, s\u00fbre et adapt\u00e9e \u00e0 chaque cas.<\/p>\n<p>Nous proposons \u00e9galement un conseil sp\u00e9cialis\u00e9 pour les bateaux inscrits en liste 6, incluant les exigences sp\u00e9cifiques pour op\u00e9rer dans des r\u00e9gions comme Valence et les Bal\u00e9ares, o\u00f9 la r\u00e9glementation r\u00e9gionale impose des d\u00e9marches suppl\u00e9mentaires pour l\u2019activit\u00e9 de location.<\/p>\n<p>Nous pouvons offrir un service int\u00e9gral couvrant toutes les \u00e9tapes du cycle de vie d\u2019un bateau, de la vente jusqu\u2019\u00e0 sa mise \u00e0 l\u2019eau.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/Tramitacion-registro-y-coordinacion-administrativa-para-embarcaciones-de-uso-particular-o-comercial.webp\u00a0\u00bb alt=\u00a0\u00bbD\u00e9marches, immatriculation et coordination administrative pour les bateaux \u00e0 usage priv\u00e9 ou commercial\u00a0\u00bb title_text=\u00a0\u00bbD\u00e9marches, immatriculation et coordination administrative pour les bateaux \u00e0 usage priv\u00e9 ou commercial\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbbottom\u00a0\u00bb animation_direction_phone=\u00a0\u00bbbottom\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|30px|30px|30px|30px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.72)\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_position=\u00a0\u00bbbottom_center\u00a0\u00bb background_blend=\u00a0\u00bbdarken\u00a0\u00bb background_video_mp4=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/02\/Ibyc-efecto-mar-1.mp4&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb custom_padding=\u00a0\u00bb|||10px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Nos services de gestion nautique<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb custom_padding=\u00a0\u00bb|||10px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/finance-icon.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbfinance-icon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong data-start=\"1733\" data-end=\"1772\">Financement et conseil fiscal<\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Accompagnement dans les aspects \u00e9conomiques et fiscaux li\u00e9s au bateau.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/sec-icon.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbsec-icon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Souscription d\u2019assurances nautiques<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Gestion et coordination de couvertures adapt\u00e9es \u00e0 un usage priv\u00e9 ou commercial.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/contrato-icono.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbicone-contrat\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Gestion documentaire et juridique<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Supervision de la documentation administrative et soutien dans les proc\u00e9dures relatives au navire.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb custom_padding=\u00a0\u00bb|||10px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/abanderamiento-icono.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbic\u00f4ne-pavillon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>D\u00e9marches d\u2019immatriculation et de pavillon<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Gestion des proc\u00e9dures n\u00e9cessaires \u00e0 l\u2019immatriculation et \u00e0 l\u2019inscription des bateaux.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/autorizacion-icono.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbautorizacion-icono\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Autorisations de navigation et de charter<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Gestion des permis et des exigences n\u00e9cessaires \u00e0 la navigation et \u00e0 l\u2019exploitation commerciale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_direction_tablet=\u00a0\u00bbleft\u00a0\u00bb animation_direction_phone=\u00a0\u00bbleft\u00a0\u00bb animation_direction_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii=\u00a0\u00bbon|25px|25px|25px|25px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/03\/engranajes-icon.png\u00a0\u00bb alt=\u00a0\u00bbic\u00f4ne\u00a0\u00bb title_text=\u00a0\u00bbengranajes-icon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>coordination et mise en \u0153uvre techniques<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbDM Sans|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Assistance durant la phase pr\u00e9c\u00e9dant la livraison et la mise en service du navire.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbAccueil\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/ibyc.es\/wp-content\/uploads\/2026\/01\/fondo-logo-transparencia.webp\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb parallax_method=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMarcellus SC|800|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032F3A\u00a0\u00bb text_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_color=\u00a0\u00bb#032F3A\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_2_text_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Notre m\u00e9thode de travail<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Une m\u00e9thode de travail fond\u00e9e sur l\u2019exp\u00e9rience, la transparence et l\u2019engagement, visant \u00e0 offrir des solutions nautiques fiables et un service personnalis\u00e9 de premier ordre.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1280px\u00a0\u00bb custom_padding=\u00a0\u00bb|||10px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10px||10px|false|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMarcellus SC|700|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb text_font_size=\u00a0\u00bb60px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>1<\/p>\n<p>[\/et_pb_text][dsm_step_flow dsm_title=\u00a0\u00bbDiagnostic initial gratuit\u00a0\u00bb dsm_content=\u00a0\u00bb<\/p>\n<p>Nous analysons chaque situation sans engagement et vous orientons vers les meilleures options.<\/p>\n<p>\u00a0\u00bb dsm_show_dir=\u00a0\u00bbon\u00a0\u00bb dsm_dir_color=\u00a0\u00bb#000000&Prime; dsm_dir_width=\u00a0\u00bb116px\u00a0\u00bb dsm_show_dir_tablet=\u00a0\u00bbon\u00a0\u00bb dsm_show_dir_phone=\u00a0\u00bboff\u00a0\u00bb dsm_show_dir_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb dsm_body_text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb dsm_body_text_text_color=\u00a0\u00bb#000000&Prime; dsm_body_text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_step_flow][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMarcellus SC|700|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb text_font_size=\u00a0\u00bb60px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>2<\/p>\n<p>[\/et_pb_text][dsm_step_flow dsm_title=\u00a0\u00bbProposition personnalis\u00e9e\u00a0\u00bb dsm_content=\u00a0\u00bb<\/p>\n<p>Nous \u00e9laborons un plan d\u2019action adapt\u00e9 \u00e0 chaque besoin juridique, fiscal, technique ou de gestion.<\/p>\n<p>\u00a0\u00bb dsm_show_dir=\u00a0\u00bbon\u00a0\u00bb dsm_dir_color=\u00a0\u00bb#000000&Prime; dsm_dir_width=\u00a0\u00bb116px\u00a0\u00bb dsm_show_dir_tablet=\u00a0\u00bbon\u00a0\u00bb dsm_show_dir_phone=\u00a0\u00bboff\u00a0\u00bb dsm_show_dir_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb dsm_body_text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb dsm_body_text_text_color=\u00a0\u00bb#000000&Prime; dsm_body_text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_step_flow][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMarcellus SC|700|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb text_font_size=\u00a0\u00bb60px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>3<\/p>\n<p>[\/et_pb_text][dsm_step_flow dsm_title=\u00a0\u00bbEx\u00e9cution rapide et transparente\u00a0\u00bb dsm_content=\u00a0\u00bb<\/p>\n<p>Nous prenons en charge toutes les d\u00e9marches, en tenant le client inform\u00e9 \u00e0 chaque \u00e9tape.<\/p>\n<p>\u00a0\u00bb dsm_show_dir=\u00a0\u00bbon\u00a0\u00bb dsm_dir_color=\u00a0\u00bb#000000&Prime; dsm_dir_width=\u00a0\u00bb116px\u00a0\u00bb dsm_show_dir_tablet=\u00a0\u00bbon\u00a0\u00bb dsm_show_dir_phone=\u00a0\u00bboff\u00a0\u00bb dsm_show_dir_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb dsm_body_text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb dsm_body_text_text_color=\u00a0\u00bb#000000&Prime; dsm_body_text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_step_flow][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbMarcellus SC|700|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#032f3a\u00a0\u00bb text_font_size=\u00a0\u00bb60px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>4<\/p>\n<p>[\/et_pb_text][dsm_step_flow dsm_title=\u00a0\u00bbSuivi et assistance continue\u00a0\u00bb dsm_content=\u00a0\u00bb<\/p>\n<p>Nous restons disponibles pour r\u00e9pondre aux questions, mettre \u00e0 jour la documentation ou \u00e9tendre les services.<\/p>\n<p>\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_font_size=\u00a0\u00bb22px\u00a0\u00bb dsm_body_text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb dsm_body_text_text_color=\u00a0\u00bb#000000&Prime; dsm_body_text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_step_flow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_block_reveal_text dsm_block_reveal_text_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm_block_reveal_text_wrapper\" data-dsm-block-reveal-animation=\"lr\" data-dsm-block-reveal-color=\"RGBA(255,255,255,0.2)\" data-dsm-block-reveal-delay=\"0.1\" data-dsm-block-reveal-viewport=\"80%\"><h1 class=\"dsm_block_reveal_text_header et_pb_module_header\">Gestion et immatriculation de bateaux de plaisance<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>D\u00e9marches, immatriculation et coordination administrative pour les bateaux \u00e0 usage priv\u00e9 ou commercial, avec une couverture nationale et internationale.Chez IBYC, nous g\u00e9rons toutes les d\u00e9marches li\u00e9es au Registre Maritime Espagnol pour les bateaux et navires de plaisance, qu\u2019ils soient destin\u00e9s \u00e0 un usage priv\u00e9 ou commercial. Nous prenons en charge les pavillons, immatriculations, changements de propri\u00e9t\u00e9, autorisations de charter, certificats, inspections et liquidations fiscales, en offrant une gestion r\u00e9active, s\u00fbre et adapt\u00e9e \u00e0 chaque cas. Nous proposons \u00e9galement un conseil sp\u00e9cialis\u00e9 pour les bateaux inscrits en liste 6, incluant les exigences sp\u00e9cifiques pour op\u00e9rer dans des r\u00e9gions comme Valence et les Bal\u00e9ares, o\u00f9 la r\u00e9glementation r\u00e9gionale impose des d\u00e9marches suppl\u00e9mentaires pour l\u2019activit\u00e9 de location. Nous pouvons offrir un service int\u00e9gral couvrant toutes les \u00e9tapes du cycle de vie d\u2019un bateau, de la vente jusqu\u2019\u00e0 sa mise \u00e0 l\u2019eau.Nos services de gestion nautiqueFinancement et conseil fiscalAccompagnement dans les aspects \u00e9conomiques et fiscaux li\u00e9s au bateau.Souscription d\u2019assurances nautiquesGestion et coordination de couvertures adapt\u00e9es \u00e0 un usage priv\u00e9 ou commercial.Gestion documentaire et juridiqueSupervision de la documentation administrative et soutien dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-460","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gestion compl\u00e8te des navires de plaisance - IBYC<\/title>\n<meta name=\"description\" content=\"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibyc.es\/fr\/gestion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion compl\u00e8te des navires de plaisance - IBYC\" \/>\n<meta property=\"og:description\" content=\"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibyc.es\/fr\/gestion\/\" \/>\n<meta property=\"og:site_name\" content=\"IBYC (Iberian Yachts Consulting SL)\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T07:45:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ibyc.es\/fr\/gestion\/\",\"url\":\"https:\/\/ibyc.es\/fr\/gestion\/\",\"name\":\"Gestion compl\u00e8te des navires de plaisance - IBYC\",\"isPartOf\":{\"@id\":\"https:\/\/ibyc.es\/fr\/#website\"},\"datePublished\":\"2026-03-26T11:08:36+00:00\",\"dateModified\":\"2026-04-30T07:45:22+00:00\",\"description\":\"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures\",\"breadcrumb\":{\"@id\":\"https:\/\/ibyc.es\/fr\/gestion\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ibyc.es\/fr\/gestion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ibyc.es\/fr\/gestion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ibyc.es\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ibyc.es\/fr\/#website\",\"url\":\"https:\/\/ibyc.es\/fr\/\",\"name\":\"IBYC (Iberian Yachts Consulting SL)\",\"description\":\"Consultor\u00eda N\u00e1utica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ibyc.es\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion compl\u00e8te des navires de plaisance - IBYC","description":"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibyc.es\/fr\/gestion\/","og_locale":"fr_FR","og_type":"article","og_title":"Gestion compl\u00e8te des navires de plaisance - IBYC","og_description":"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures","og_url":"https:\/\/ibyc.es\/fr\/gestion\/","og_site_name":"IBYC (Iberian Yachts Consulting SL)","article_modified_time":"2026-04-30T07:45:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibyc.es\/fr\/gestion\/","url":"https:\/\/ibyc.es\/fr\/gestion\/","name":"Gestion compl\u00e8te des navires de plaisance - IBYC","isPartOf":{"@id":"https:\/\/ibyc.es\/fr\/#website"},"datePublished":"2026-03-26T11:08:36+00:00","dateModified":"2026-04-30T07:45:22+00:00","description":"Gestion compl\u00e8te des navires de plaisance : immatriculation, pavillon, permis, affr\u00e8tement, documentation et proc\u00e9dures","breadcrumb":{"@id":"https:\/\/ibyc.es\/fr\/gestion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibyc.es\/fr\/gestion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ibyc.es\/fr\/gestion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibyc.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Gestion"}]},{"@type":"WebSite","@id":"https:\/\/ibyc.es\/fr\/#website","url":"https:\/\/ibyc.es\/fr\/","name":"IBYC (Iberian Yachts Consulting SL)","description":"Consultor\u00eda N\u00e1utica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibyc.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/pages\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":2,"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/pages\/460\/revisions"}],"predecessor-version":[{"id":463,"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/pages\/460\/revisions\/463"}],"wp:attachment":[{"href":"https:\/\/ibyc.es\/fr\/wp-json\/wp\/v2\/media?parent=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}